{"id":7359,"date":"2023-06-05T13:34:11","date_gmt":"2023-06-05T11:34:11","guid":{"rendered":"https:\/\/ispgestion.com\/?p=7359"},"modified":"2023-06-09T08:41:13","modified_gmt":"2023-06-09T06:41:13","slug":"novedades-app-isp-gestion-v1-0-21","status":"publish","type":"post","link":"https:\/\/ispgestion.com\/pt\/novedades-app-isp-gestion-v1-0-21\/","title":{"rendered":"Aplicativo de not\u00edcias ISP Management v1.0.21"},"content":{"rendered":"<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/0HFRgbxqBuo\" title=\"reprodutor de v\u00eddeo do youtube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">Novidades e melhorias em nosso App para dispositivos m\u00f3veis:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=c7p4pzp1ock&amp;t=9s\">00:09<\/a> \u2013 Novas formas de pagamento (App)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Novidades e melhorias em nosso App para dispositivos m\u00f3veis:<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[20],"tags":[],"class_list":["post-7359","post","type-post","status-publish","format-standard","hentry","category-app"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novedades App ISP Gesti\u00f3n v1.0.21 - ISP Gesti\u00f3n<\/title>\n<meta name=\"description\" content=\"Novedades y mejoras en nuestra App para dispositivos m\u00f3viles de ISP Gesti\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ispgestion.com\/pt\/novedades-app-isp-gestion-v1-0-21\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novedades App ISP Gesti\u00f3n v1.0.21 - ISP Gesti\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Novedades y mejoras en nuestra App para dispositivos m\u00f3viles de ISP Gesti\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ispgestion.com\/pt\/novedades-app-isp-gestion-v1-0-21\/\" \/>\n<meta property=\"og:site_name\" content=\"ISP Gesti\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ispgestion\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T11:34:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T06:41:13+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Montes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Montes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/\"},\"author\":{\"name\":\"Francisco Montes\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#\\\/schema\\\/person\\\/66b22ed56c2e9904060a201bc95b16cc\"},\"headline\":\"Novedades App ISP Gesti\u00f3n v1.0.21\",\"datePublished\":\"2023-06-05T11:34:11+00:00\",\"dateModified\":\"2023-06-09T06:41:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/\"},\"wordCount\":22,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#organization\"},\"articleSection\":[\"App\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/\",\"url\":\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/\",\"name\":\"Novedades App ISP Gesti\u00f3n v1.0.21 - ISP Gesti\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#website\"},\"datePublished\":\"2023-06-05T11:34:11+00:00\",\"dateModified\":\"2023-06-09T06:41:13+00:00\",\"description\":\"Novedades y mejoras en nuestra App para dispositivos m\u00f3viles de ISP Gesti\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/novedades-app-isp-gestion-v1-0-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ispgestion.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades App ISP Gesti\u00f3n v1.0.21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#website\",\"url\":\"https:\\\/\\\/ispgestion.com\\\/\",\"name\":\"ISP Gesti\u00f3n\",\"description\":\"Software en la nube para ISP - Sotware ERP\",\"publisher\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ispgestion.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#organization\",\"name\":\"ISP Gesti\u00f3n\",\"url\":\"https:\\\/\\\/ispgestion.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ispgestion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-logo-isp-1-1.png\",\"contentUrl\":\"https:\\\/\\\/ispgestion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-logo-isp-1-1.png\",\"width\":245,\"height\":250,\"caption\":\"ISP Gesti\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ispgestion\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/isp-gesti\u00f3n-62652715a\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkZAs-0NFnSnVrh17SNCARg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#\\\/schema\\\/person\\\/66b22ed56c2e9904060a201bc95b16cc\",\"name\":\"Francisco Montes\",\"sameAs\":[\"http:\\\/\\\/ispgestion.com\"],\"url\":\"https:\\\/\\\/ispgestion.com\\\/pt\\\/author\\\/francisco-montes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novedades App ISP Gesti\u00f3n v1.0.21 - ISP Gesti\u00f3n","description":"Novedades y mejoras en nuestra App para dispositivos m\u00f3viles de ISP Gesti\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ispgestion.com\/pt\/novedades-app-isp-gestion-v1-0-21\/","og_locale":"pt_PT","og_type":"article","og_title":"Novedades App ISP Gesti\u00f3n v1.0.21 - ISP Gesti\u00f3n","og_description":"Novedades y mejoras en nuestra App para dispositivos m\u00f3viles de ISP Gesti\u00f3n.","og_url":"https:\/\/ispgestion.com\/pt\/novedades-app-isp-gestion-v1-0-21\/","og_site_name":"ISP Gesti\u00f3n","article_publisher":"https:\/\/www.facebook.com\/ispgestion\/","article_published_time":"2023-06-05T11:34:11+00:00","article_modified_time":"2023-06-09T06:41:13+00:00","author":"Francisco Montes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Francisco Montes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/#article","isPartOf":{"@id":"https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/"},"author":{"name":"Francisco Montes","@id":"https:\/\/ispgestion.com\/#\/schema\/person\/66b22ed56c2e9904060a201bc95b16cc"},"headline":"Novedades App ISP Gesti\u00f3n v1.0.21","datePublished":"2023-06-05T11:34:11+00:00","dateModified":"2023-06-09T06:41:13+00:00","mainEntityOfPage":{"@id":"https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/"},"wordCount":22,"commentCount":0,"publisher":{"@id":"https:\/\/ispgestion.com\/#organization"},"articleSection":["App"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/","url":"https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/","name":"Novedades App ISP Gesti\u00f3n v1.0.21 - ISP Gesti\u00f3n","isPartOf":{"@id":"https:\/\/ispgestion.com\/#website"},"datePublished":"2023-06-05T11:34:11+00:00","dateModified":"2023-06-09T06:41:13+00:00","description":"Novedades y mejoras en nuestra App para dispositivos m\u00f3viles de ISP Gesti\u00f3n.","breadcrumb":{"@id":"https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ispgestion.com\/novedades-app-isp-gestion-v1-0-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ispgestion.com\/"},{"@type":"ListItem","position":2,"name":"Novedades App ISP Gesti\u00f3n v1.0.21"}]},{"@type":"WebSite","@id":"https:\/\/ispgestion.com\/#website","url":"https:\/\/ispgestion.com\/","name":"ISP Gesti\u00f3n","description":"Software em Nuvem para ISP - Software ERP","publisher":{"@id":"https:\/\/ispgestion.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ispgestion.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/ispgestion.com\/#organization","name":"ISP Gesti\u00f3n","url":"https:\/\/ispgestion.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ispgestion.com\/#\/schema\/logo\/image\/","url":"https:\/\/ispgestion.com\/wp-content\/uploads\/2020\/04\/cropped-logo-isp-1-1.png","contentUrl":"https:\/\/ispgestion.com\/wp-content\/uploads\/2020\/04\/cropped-logo-isp-1-1.png","width":245,"height":250,"caption":"ISP Gesti\u00f3n"},"image":{"@id":"https:\/\/ispgestion.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ispgestion\/","https:\/\/es.linkedin.com\/in\/isp-gesti\u00f3n-62652715a","https:\/\/www.youtube.com\/channel\/UCkZAs-0NFnSnVrh17SNCARg"]},{"@type":"Person","@id":"https:\/\/ispgestion.com\/#\/schema\/person\/66b22ed56c2e9904060a201bc95b16cc","name":"Francisco Montes","sameAs":["http:\/\/ispgestion.com"],"url":"https:\/\/ispgestion.com\/pt\/author\/francisco-montes\/"}]}},"_links":{"self":[{"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/posts\/7359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/comments?post=7359"}],"version-history":[{"count":1,"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/posts\/7359\/revisions"}],"predecessor-version":[{"id":7360,"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/posts\/7359\/revisions\/7360"}],"wp:attachment":[{"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/media?parent=7359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/categories?post=7359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ispgestion.com\/pt\/wp-json\/wp\/v2\/tags?post=7359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}