{"id":268,"date":"2020-04-03T08:58:11","date_gmt":"2020-04-03T06:58:11","guid":{"rendered":"http:\/\/ispgestion.com\/?page_id=268"},"modified":"2022-03-12T10:14:00","modified_gmt":"2022-03-12T09:14:00","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/ispgestion.com\/it\/39363-home\/politica-de-cookies\/","title":{"rendered":"Informativa sui cookie"},"content":{"rendered":"<p><strong>INFORMATIVA SUI COOKIE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li><strong><u>USO DE COOKIES<\/u><\/strong><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>El sitio web de ISPGESTI\u00d3N PROVIDER S.L. utiliza cookies propias y de terceros para permitir el funcionamiento de la misma adem\u00e1s de obtener y analizar la informaci\u00f3n referente a la navegaci\u00f3n por el sitio Web.<\/p>\n<p>&nbsp;<\/p>\n<p>Con la mera navegaci\u00f3n (con el navegador habilitado para aceptar cookies) el usuario acepta la instalaci\u00f3n de cookies, salvo que se oponga a ello.<\/p>\n<p>&nbsp;<\/p>\n<p>Nuestra Pol\u00edtica de Cookies est\u00e1 sujeta a actualizaciones peri\u00f3dicas. Su prop\u00f3sito es ayudarle a comprender el uso que hacemos de las cookies, la finalidad de las cookies utilizadas, as\u00ed como las opciones que tiene el usuario para gestionarlas.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li><strong><u>\u00bfQU\u00c9 ES UNA COOKIE? Y SUS TIPOS<\/u><\/strong><\/li>\n<\/ol>\n<p>Una \u201cCookie\u201d es un peque\u00f1o archivo de texto que un sitio web almacena en el navegador del usuario. Las cookies&nbsp;facilitan el uso y la navegaci\u00f3n por una p\u00e1gina web&nbsp;y son esenciales para el funcionamiento de internet, aportando innumerables ventajas en la prestaci\u00f3n de servicios interactivos.<\/p>\n<p>Seg\u00fan la entidad que las gestione:<\/p>\n<ul>\n<li><strong>Cookies propias<\/strong>: son aquellas que se env\u00edan al equipo terminal del usuario desde un equipo o dominio gestionado por el propio editor y desde que se presta el servicio solicitado por el Usuario.<\/li>\n<li><strong>Cookies de terceros<\/strong>: son aquellas que se env\u00edan al equipo terminal del Usuario desde un equipo o dominio que no es gestionado por el editor, sino por otra entidad que trata los datos obtenidos a trav\u00e9s de las cookies.<\/li>\n<\/ul>\n<p>Seg\u00fan su finalidad:<\/p>\n<ul>\n<li><strong>Cookies t\u00e9cnicas:<\/strong>son aquellas que permiten o facilitan al Usuario la navegaci\u00f3n a trav\u00e9s de la p\u00e1gina web y la utilizaci\u00f3n de las diferentes opciones o servicios que en ella existan, como identificar la sesi\u00f3n o recordar contrase\u00f1as.<\/li>\n<li><strong>Cookies de an\u00e1lisis<\/strong>: son aquellas que, bien tratadas por nosotros o por terceros, nos permiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del servicio ofertado. Para ellos se analiza su navegaci\u00f3n en nuestra p\u00e1gina web con el fin de mejorar la oferta de productos o servicios que le ofrecemos.<\/li>\n<\/ul>\n<p>Seg\u00fan el plazo de tiempo que permanecen activadas:<\/p>\n<ul>\n<li><strong>Cookies de sesi\u00f3n<\/strong>: son cookies temporales que permanecen en el archivo de cookies de su navegador hasta que abandone la p\u00e1gina web, por lo que ninguna queda registrada en el disco duro del usuario. La informaci\u00f3n obtenida por medio de estas cookies sirve para analizar las pautas de tr\u00e1fico de la web. A la larga, esto nos permite proporcionar una mejor experiencia para mejorar el contenido y facilitar su uso.<\/li>\n<li><strong>Cookies permanentes<\/strong>: son almacenadas en el disco duro y nuestra web las lee cada vez que el usuario realiza una nueva visita. Una cookie permanente puede ser accedida y tratada durante un periodo definido por el responsable de la cookie, despu\u00e9s de esa fecha dejar\u00e1 de funcionar.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ol start=\"3\">\n<li><strong><u>COOKIES UTILIZADAS EN EL SITIO WEB DE ISPGESTI\u00d3N PROVIDER S.L.<\/u><\/strong><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>COOKIES T\u00c9CNICAS<\/strong><\/p>\n<p>Esta web utiliza cookies de uso interno para el funcionamiento de la web.<\/p>\n<p><strong>Nome<\/strong>: PHPSESSID<br \/>\n<strong>Caduca<\/strong>: sesi\u00f3n.<br \/>\nDominio: Propia<br \/>\n<strong>Descripci\u00f3n<\/strong>: Esta cookie es usado por el lenguaje de encriptado PHP para permitir que las variables de sesi\u00f3n sean guardadas en el servidor web. Esta cookie es esencial para el funcionamiento de la web.<\/p>\n<p><strong>COOKIES ANAL\u00cdTICAS<br \/>\n<\/strong>Esta web utiliza cookies anal\u00edticas de terceros, Google Analytics, para obtener y analizar la informaci\u00f3n referente a la navegaci\u00f3n por el sitio Web.&nbsp; ISPGESTI\u00d3N PROVIDER S.L. puede utilizar estos datos para mejorar sus propios servicios. Puedes obtener m\u00e1s informaci\u00f3n en el siguiente enlace: <a href=\"https:\/\/marketingplatform.google.com\/about\/analytics\/\">www.google.com\/analytics\/<\/a>.<\/p>\n<p>En concreto utilizamos las siguientes cookies.<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>Nome<\/strong>: 1P_JAR<br \/>\n<strong>Caduca<\/strong>: 1 semana desde que se cre\u00f3 inicialmente o se restableci\u00f3.<br \/>\n<strong>Dominio:<\/strong>&nbsp;www.google.com<br \/>\n<strong>Descripci\u00f3n<\/strong>: Transfiere datos a Google.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>Nome<\/strong>: CONSENT<br \/>\n<strong>Caduca<\/strong>: 20 a\u00f1os desde que se cre\u00f3 inicialmente o se restableci\u00f3.<br \/>\n<strong>Dominio:<\/strong>&nbsp;www.google.es<br \/>\n<strong>Descripci\u00f3n<\/strong>: Cookie de Google.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<ol start=\"4\">\n<li><strong><u>GARANT\u00cdAS Y OPCIONES SOBRE LAS COOKIES<\/u><\/strong><\/li>\n<\/ol>\n<p>En todo momento, y al menos, durante la instalaci\u00f3n o puesta al d\u00eda del navegador,&nbsp;el usuario tiene la posibilidad de aceptar o rechazar la instalaci\u00f3n de cookies, o bien rechazar la instalaci\u00f3n de las cookies de terceros. Adem\u00e1s, despu\u00e9s de cada sesi\u00f3n puede eliminar todas o algunas de las cookies almacenadas. Asimismo, el usuario puede activar:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>La navegaci\u00f3n privada, mediante la cual su navegador deja de guardar el historial de navegaci\u00f3n, contrase\u00f1as de sitios web, cookies y otra informaci\u00f3n de las p\u00e1ginas que visita, o<\/li>\n<li>La funci\u00f3n de no rastrear, por la que el navegador pide a los sitios web que visita que no rastreen sus h\u00e1bitos de navegaci\u00f3n, para, por ejemplo, servirle publicidad de su inter\u00e9s en los sitios que visita.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Le recomendamos que consulte la ayuda de su navegador para informarse de las diferentes opciones sobre c\u00f3mo gestionar las cookies. A continuaci\u00f3n, incluimos los v\u00ednculos para gestionar cookies en los navegadores m\u00e1s relevantes:<\/p>\n<ul>\n<li>Chrome:&nbsp;<a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=es\">http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647<\/a><\/li>\n<li>Firefox:&nbsp;<a href=\"https:\/\/support.mozilla.org\/es\/kb\/Borrar%20cookies\">Limpiar cookies en firefox<\/a><\/li>\n<li>Internet Explorer:&nbsp;<a href=\"https:\/\/support.microsoft.com\/es-es\/windows\/eliminar-y-administrar-cookies-168dab11-0753-043d-7c16-ede5947fc64d\">Eliminar y administrar cookies Microsoft<\/a><\/li>\n<li>Safari:&nbsp;<a href=\"https:\/\/www.apple.com\/legal\/privacy\/es\/cookies\/\">https:\/\/www.apple.com\/legal\/privacy\/es\/cookies\/<\/a><\/li>\n<\/ul>\n<p>El usuario puede revocar su consentimiento para el uso de cookies en su navegador a trav\u00e9s de las opciones de configuraci\u00f3n, as\u00ed como a trav\u00e9s de los enlaces de terceros.<\/p>\n<p>Si no quiere que Google Analytics recoja y utilice informaci\u00f3n puede instalar un sistema de rechazo en su navegador a trav\u00e9s del siguiente enlace:&nbsp; <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=None\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=None<\/a><\/p>\n<p>ATENCI\u00d3N: Tenga en cuenta que el bloqueo de cookies puede afectar a todas o algunas de las funcionalidades de nuestra web.<\/p>","protected":false},"excerpt":{"rendered":"<p>POL\u00cdTICA DE COOKIES &nbsp; USO DE COOKIES &nbsp; El sitio web de ISPGESTI\u00d3N PROVIDER S.L. utiliza cookies propias y de terceros para permitir el funcionamiento de la misma adem\u00e1s de obtener y analizar la informaci\u00f3n referente a la navegaci\u00f3n por el sitio Web. &nbsp; Con la mera navegaci\u00f3n (con el navegador habilitado para aceptar cookies) el usuario acepta la instalaci\u00f3n de cookies, salvo que se oponga a ello. &nbsp; Nuestra Pol\u00edtica de Cookies est\u00e1 sujeta a actualizaciones peri\u00f3dicas. Su prop\u00f3sito es ayudarle a comprender el uso que hacemos de las cookies, la finalidad de las cookies utilizadas, as\u00ed como las opciones que tiene el usuario para gestionarlas. &nbsp; \u00bfQU\u00c9 ES UNA COOKIE? Y SUS TIPOS Una \u201cCookie\u201d es un peque\u00f1o archivo de texto que un sitio web almacena en el navegador del usuario. Las cookies&nbsp;facilitan el uso y la navegaci\u00f3n por una p\u00e1gina web&nbsp;y son esenciales para el funcionamiento de internet, aportando innumerables ventajas en la prestaci\u00f3n de servicios interactivos. Seg\u00fan la entidad que las gestione: Cookies propias: son aquellas que se env\u00edan al equipo terminal del usuario desde un equipo o dominio gestionado por el propio editor y desde que se presta el servicio solicitado por el Usuario. Cookies de terceros: son aquellas que se env\u00edan al equipo terminal del Usuario desde un equipo o dominio que no es gestionado por el editor, sino por otra entidad que trata los datos obtenidos a trav\u00e9s de las cookies. Seg\u00fan su finalidad: Cookies t\u00e9cnicas:son aquellas que permiten o facilitan al Usuario la navegaci\u00f3n a trav\u00e9s de la p\u00e1gina web y la utilizaci\u00f3n de las diferentes opciones o servicios que en ella existan, como identificar la sesi\u00f3n o recordar contrase\u00f1as. Cookies de an\u00e1lisis: son aquellas que, bien tratadas por nosotros o por terceros, nos permiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del servicio ofertado. Para ellos se analiza su navegaci\u00f3n en nuestra p\u00e1gina web con el fin de mejorar la oferta de productos o servicios que le ofrecemos. Seg\u00fan el plazo de tiempo que permanecen activadas: Cookies de sesi\u00f3n: son cookies temporales que permanecen en el archivo de cookies de su navegador hasta que abandone la p\u00e1gina web, por lo que ninguna queda registrada en el disco duro del usuario. La informaci\u00f3n obtenida por medio de estas cookies sirve para analizar las pautas de tr\u00e1fico de la web. A la larga, esto nos permite proporcionar una mejor experiencia para mejorar el contenido y facilitar su uso. Cookies permanentes: son almacenadas en el disco duro y nuestra web las lee cada vez que el usuario realiza una nueva visita. Una cookie permanente puede ser accedida y tratada durante un periodo definido por el responsable de la cookie, despu\u00e9s de esa fecha dejar\u00e1 de funcionar. &nbsp; COOKIES UTILIZADAS EN EL SITIO WEB DE ISPGESTI\u00d3N PROVIDER S.L. &nbsp; COOKIES T\u00c9CNICAS Esta web utiliza cookies de uso interno para el funcionamiento de la web. Nombre: PHPSESSID Caduca: sesi\u00f3n. Dominio: Propia Descripci\u00f3n: Esta cookie es usado por el lenguaje de encriptado PHP para permitir que las variables de sesi\u00f3n sean guardadas en el servidor web. Esta cookie es esencial para el funcionamiento de la web. COOKIES ANAL\u00cdTICAS Esta web utiliza cookies anal\u00edticas de terceros, Google Analytics, para obtener y analizar la informaci\u00f3n referente a la navegaci\u00f3n por el sitio Web.&nbsp; ISPGESTI\u00d3N PROVIDER S.L. puede utilizar estos datos para mejorar sus propios servicios. Puedes obtener m\u00e1s informaci\u00f3n en el siguiente enlace: www.google.com\/analytics\/. En concreto utilizamos las siguientes cookies. &nbsp; Nombre: 1P_JAR Caduca: 1 semana desde que se cre\u00f3 inicialmente o se restableci\u00f3. Dominio:&nbsp;www.google.com Descripci\u00f3n: Transfiere datos a Google. &nbsp; &nbsp; Nombre: CONSENT Caduca: 20 a\u00f1os desde que se cre\u00f3 inicialmente o se restableci\u00f3. Dominio:&nbsp;www.google.es Descripci\u00f3n: Cookie de Google. &nbsp; &nbsp; GARANT\u00cdAS Y OPCIONES SOBRE LAS COOKIES En todo momento, y al menos, durante la instalaci\u00f3n o puesta al d\u00eda del navegador,&nbsp;el usuario tiene la posibilidad de aceptar o rechazar la instalaci\u00f3n de cookies, o bien rechazar la instalaci\u00f3n de las cookies de terceros. Adem\u00e1s, despu\u00e9s de cada sesi\u00f3n puede eliminar todas o algunas de las cookies almacenadas. Asimismo, el usuario puede activar: &nbsp; La navegaci\u00f3n privada, mediante la cual su navegador deja de guardar el historial de navegaci\u00f3n, contrase\u00f1as de sitios web, cookies y otra informaci\u00f3n de las p\u00e1ginas que visita, o La funci\u00f3n de no rastrear, por la que el navegador pide a los sitios web que visita que no rastreen sus h\u00e1bitos de navegaci\u00f3n, para, por ejemplo, servirle publicidad de su inter\u00e9s en los sitios que visita. &nbsp; Le recomendamos que consulte la ayuda de su navegador para informarse de las diferentes opciones sobre c\u00f3mo gestionar las cookies. A continuaci\u00f3n, incluimos los v\u00ednculos para gestionar cookies en los navegadores m\u00e1s relevantes: Chrome:&nbsp;http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647 Firefox:&nbsp;Limpiar cookies en firefox Internet Explorer:&nbsp;Eliminar y administrar cookies Microsoft Safari:&nbsp;https:\/\/www.apple.com\/legal\/privacy\/es\/cookies\/ El usuario puede revocar su consentimiento para el uso de cookies en su navegador a trav\u00e9s de las opciones de configuraci\u00f3n, as\u00ed como a trav\u00e9s de los enlaces de terceros. Si no quiere que Google Analytics recoja y utilice informaci\u00f3n puede instalar un sistema de rechazo en su navegador a trav\u00e9s del siguiente enlace:&nbsp; https:\/\/tools.google.com\/dlpage\/gaoptout?hl=None ATENCI\u00d3N: Tenga en cuenta que el bloqueo de cookies puede afectar a todas o algunas de las funcionalidades de nuestra web.<\/p>","protected":false},"author":1,"featured_media":0,"parent":40,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"full-width","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-268","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Cookies - ISP Gesti\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ispgestion.com\/it\/39363-home\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Cookies - ISP Gesti\u00f3n\" \/>\n<meta property=\"og:description\" content=\"POL\u00cdTICA DE COOKIES &nbsp; USO DE COOKIES &nbsp; El sitio web de ISPGESTI\u00d3N PROVIDER S.L. utiliza cookies propias y de terceros para permitir el funcionamiento de la misma adem\u00e1s de obtener y analizar la informaci\u00f3n referente a la navegaci\u00f3n por el sitio Web. &nbsp; Con la mera navegaci\u00f3n (con el navegador habilitado para aceptar cookies) el usuario acepta la instalaci\u00f3n de cookies, salvo que se oponga a ello. &nbsp; Nuestra Pol\u00edtica de Cookies est\u00e1 sujeta a actualizaciones peri\u00f3dicas. Su prop\u00f3sito es ayudarle a comprender el uso que hacemos de las cookies, la finalidad de las cookies utilizadas, as\u00ed como las opciones que tiene el usuario para gestionarlas. &nbsp; \u00bfQU\u00c9 ES UNA COOKIE? Y SUS TIPOS Una \u201cCookie\u201d es un peque\u00f1o archivo de texto que un sitio web almacena en el navegador del usuario. Las cookies&nbsp;facilitan el uso y la navegaci\u00f3n por una p\u00e1gina web&nbsp;y son esenciales para el funcionamiento de internet, aportando innumerables ventajas en la prestaci\u00f3n de servicios interactivos. Seg\u00fan la entidad que las gestione: Cookies propias: son aquellas que se env\u00edan al equipo terminal del usuario desde un equipo o dominio gestionado por el propio editor y desde que se presta el servicio solicitado por el Usuario. Cookies de terceros: son aquellas que se env\u00edan al equipo terminal del Usuario desde un equipo o dominio que no es gestionado por el editor, sino por otra entidad que trata los datos obtenidos a trav\u00e9s de las cookies. Seg\u00fan su finalidad: Cookies t\u00e9cnicas:son aquellas que permiten o facilitan al Usuario la navegaci\u00f3n a trav\u00e9s de la p\u00e1gina web y la utilizaci\u00f3n de las diferentes opciones o servicios que en ella existan, como identificar la sesi\u00f3n o recordar contrase\u00f1as. Cookies de an\u00e1lisis: son aquellas que, bien tratadas por nosotros o por terceros, nos permiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del servicio ofertado. Para ellos se analiza su navegaci\u00f3n en nuestra p\u00e1gina web con el fin de mejorar la oferta de productos o servicios que le ofrecemos. Seg\u00fan el plazo de tiempo que permanecen activadas: Cookies de sesi\u00f3n: son cookies temporales que permanecen en el archivo de cookies de su navegador hasta que abandone la p\u00e1gina web, por lo que ninguna queda registrada en el disco duro del usuario. La informaci\u00f3n obtenida por medio de estas cookies sirve para analizar las pautas de tr\u00e1fico de la web. A la larga, esto nos permite proporcionar una mejor experiencia para mejorar el contenido y facilitar su uso. Cookies permanentes: son almacenadas en el disco duro y nuestra web las lee cada vez que el usuario realiza una nueva visita. Una cookie permanente puede ser accedida y tratada durante un periodo definido por el responsable de la cookie, despu\u00e9s de esa fecha dejar\u00e1 de funcionar. &nbsp; COOKIES UTILIZADAS EN EL SITIO WEB DE ISPGESTI\u00d3N PROVIDER S.L. &nbsp; COOKIES T\u00c9CNICAS Esta web utiliza cookies de uso interno para el funcionamiento de la web. Nombre: PHPSESSID Caduca: sesi\u00f3n. Dominio: Propia Descripci\u00f3n: Esta cookie es usado por el lenguaje de encriptado PHP para permitir que las variables de sesi\u00f3n sean guardadas en el servidor web. Esta cookie es esencial para el funcionamiento de la web. COOKIES ANAL\u00cdTICAS Esta web utiliza cookies anal\u00edticas de terceros, Google Analytics, para obtener y analizar la informaci\u00f3n referente a la navegaci\u00f3n por el sitio Web.&nbsp; ISPGESTI\u00d3N PROVIDER S.L. puede utilizar estos datos para mejorar sus propios servicios. Puedes obtener m\u00e1s informaci\u00f3n en el siguiente enlace: www.google.com\/analytics\/. En concreto utilizamos las siguientes cookies. &nbsp; Nombre: 1P_JAR Caduca: 1 semana desde que se cre\u00f3 inicialmente o se restableci\u00f3. Dominio:&nbsp;www.google.com Descripci\u00f3n: Transfiere datos a Google. &nbsp; &nbsp; Nombre: CONSENT Caduca: 20 a\u00f1os desde que se cre\u00f3 inicialmente o se restableci\u00f3. Dominio:&nbsp;www.google.es Descripci\u00f3n: Cookie de Google. &nbsp; &nbsp; GARANT\u00cdAS Y OPCIONES SOBRE LAS COOKIES En todo momento, y al menos, durante la instalaci\u00f3n o puesta al d\u00eda del navegador,&nbsp;el usuario tiene la posibilidad de aceptar o rechazar la instalaci\u00f3n de cookies, o bien rechazar la instalaci\u00f3n de las cookies de terceros. Adem\u00e1s, despu\u00e9s de cada sesi\u00f3n puede eliminar todas o algunas de las cookies almacenadas. Asimismo, el usuario puede activar: &nbsp; La navegaci\u00f3n privada, mediante la cual su navegador deja de guardar el historial de navegaci\u00f3n, contrase\u00f1as de sitios web, cookies y otra informaci\u00f3n de las p\u00e1ginas que visita, o La funci\u00f3n de no rastrear, por la que el navegador pide a los sitios web que visita que no rastreen sus h\u00e1bitos de navegaci\u00f3n, para, por ejemplo, servirle publicidad de su inter\u00e9s en los sitios que visita. &nbsp; Le recomendamos que consulte la ayuda de su navegador para informarse de las diferentes opciones sobre c\u00f3mo gestionar las cookies. A continuaci\u00f3n, incluimos los v\u00ednculos para gestionar cookies en los navegadores m\u00e1s relevantes: Chrome:&nbsp;http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647 Firefox:&nbsp;Limpiar cookies en firefox Internet Explorer:&nbsp;Eliminar y administrar cookies Microsoft Safari:&nbsp;https:\/\/www.apple.com\/legal\/privacy\/es\/cookies\/ El usuario puede revocar su consentimiento para el uso de cookies en su navegador a trav\u00e9s de las opciones de configuraci\u00f3n, as\u00ed como a trav\u00e9s de los enlaces de terceros. Si no quiere que Google Analytics recoja y utilice informaci\u00f3n puede instalar un sistema de rechazo en su navegador a trav\u00e9s del siguiente enlace:&nbsp; https:\/\/tools.google.com\/dlpage\/gaoptout?hl=None ATENCI\u00d3N: Tenga en cuenta que el bloqueo de cookies puede afectar a todas o algunas de las funcionalidades de nuestra web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ispgestion.com\/it\/39363-home\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"ISP Gesti\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ispgestion\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-12T09:14:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/39363-home\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/ispgestion.com\\\/39363-home\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de Cookies - ISP Gesti\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#website\"},\"datePublished\":\"2020-04-03T06:58:11+00:00\",\"dateModified\":\"2022-03-12T09:14:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/39363-home\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ispgestion.com\\\/39363-home\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/39363-home\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ispgestion.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home, Isp Gesti\u00f3n\",\"item\":\"https:\\\/\\\/ispgestion.com\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pol\u00edtica de Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#website\",\"url\":\"https:\\\/\\\/ispgestion.com\\\/\",\"name\":\"ISP Gesti\u00f3n\",\"description\":\"Software en la nube para ISP - Sotware ERP\",\"publisher\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ispgestion.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#organization\",\"name\":\"ISP Gesti\u00f3n\",\"url\":\"https:\\\/\\\/ispgestion.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ispgestion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-logo-isp-1-1.png\",\"contentUrl\":\"https:\\\/\\\/ispgestion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-logo-isp-1-1.png\",\"width\":245,\"height\":250,\"caption\":\"ISP Gesti\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/ispgestion.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ispgestion\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/isp-gesti\u00f3n-62652715a\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkZAs-0NFnSnVrh17SNCARg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Cookies - ISP Gesti\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ispgestion.com\/it\/39363-home\/politica-de-cookies\/","og_locale":"it_IT","og_type":"article","og_title":"Pol\u00edtica de Cookies - ISP Gesti\u00f3n","og_description":"POL\u00cdTICA DE COOKIES &nbsp; USO DE COOKIES &nbsp; El sitio web de ISPGESTI\u00d3N PROVIDER S.L. utiliza cookies propias y de terceros para permitir el funcionamiento de la misma adem\u00e1s de obtener y analizar la informaci\u00f3n referente a la navegaci\u00f3n por el sitio Web. &nbsp; Con la mera navegaci\u00f3n (con el navegador habilitado para aceptar cookies) el usuario acepta la instalaci\u00f3n de cookies, salvo que se oponga a ello. &nbsp; Nuestra Pol\u00edtica de Cookies est\u00e1 sujeta a actualizaciones peri\u00f3dicas. Su prop\u00f3sito es ayudarle a comprender el uso que hacemos de las cookies, la finalidad de las cookies utilizadas, as\u00ed como las opciones que tiene el usuario para gestionarlas. &nbsp; \u00bfQU\u00c9 ES UNA COOKIE? Y SUS TIPOS Una \u201cCookie\u201d es un peque\u00f1o archivo de texto que un sitio web almacena en el navegador del usuario. Las cookies&nbsp;facilitan el uso y la navegaci\u00f3n por una p\u00e1gina web&nbsp;y son esenciales para el funcionamiento de internet, aportando innumerables ventajas en la prestaci\u00f3n de servicios interactivos. Seg\u00fan la entidad que las gestione: Cookies propias: son aquellas que se env\u00edan al equipo terminal del usuario desde un equipo o dominio gestionado por el propio editor y desde que se presta el servicio solicitado por el Usuario. Cookies de terceros: son aquellas que se env\u00edan al equipo terminal del Usuario desde un equipo o dominio que no es gestionado por el editor, sino por otra entidad que trata los datos obtenidos a trav\u00e9s de las cookies. Seg\u00fan su finalidad: Cookies t\u00e9cnicas:son aquellas que permiten o facilitan al Usuario la navegaci\u00f3n a trav\u00e9s de la p\u00e1gina web y la utilizaci\u00f3n de las diferentes opciones o servicios que en ella existan, como identificar la sesi\u00f3n o recordar contrase\u00f1as. Cookies de an\u00e1lisis: son aquellas que, bien tratadas por nosotros o por terceros, nos permiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del servicio ofertado. Para ellos se analiza su navegaci\u00f3n en nuestra p\u00e1gina web con el fin de mejorar la oferta de productos o servicios que le ofrecemos. Seg\u00fan el plazo de tiempo que permanecen activadas: Cookies de sesi\u00f3n: son cookies temporales que permanecen en el archivo de cookies de su navegador hasta que abandone la p\u00e1gina web, por lo que ninguna queda registrada en el disco duro del usuario. La informaci\u00f3n obtenida por medio de estas cookies sirve para analizar las pautas de tr\u00e1fico de la web. A la larga, esto nos permite proporcionar una mejor experiencia para mejorar el contenido y facilitar su uso. Cookies permanentes: son almacenadas en el disco duro y nuestra web las lee cada vez que el usuario realiza una nueva visita. Una cookie permanente puede ser accedida y tratada durante un periodo definido por el responsable de la cookie, despu\u00e9s de esa fecha dejar\u00e1 de funcionar. &nbsp; COOKIES UTILIZADAS EN EL SITIO WEB DE ISPGESTI\u00d3N PROVIDER S.L. &nbsp; COOKIES T\u00c9CNICAS Esta web utiliza cookies de uso interno para el funcionamiento de la web. Nombre: PHPSESSID Caduca: sesi\u00f3n. Dominio: Propia Descripci\u00f3n: Esta cookie es usado por el lenguaje de encriptado PHP para permitir que las variables de sesi\u00f3n sean guardadas en el servidor web. Esta cookie es esencial para el funcionamiento de la web. COOKIES ANAL\u00cdTICAS Esta web utiliza cookies anal\u00edticas de terceros, Google Analytics, para obtener y analizar la informaci\u00f3n referente a la navegaci\u00f3n por el sitio Web.&nbsp; ISPGESTI\u00d3N PROVIDER S.L. puede utilizar estos datos para mejorar sus propios servicios. Puedes obtener m\u00e1s informaci\u00f3n en el siguiente enlace: www.google.com\/analytics\/. En concreto utilizamos las siguientes cookies. &nbsp; Nombre: 1P_JAR Caduca: 1 semana desde que se cre\u00f3 inicialmente o se restableci\u00f3. Dominio:&nbsp;www.google.com Descripci\u00f3n: Transfiere datos a Google. &nbsp; &nbsp; Nombre: CONSENT Caduca: 20 a\u00f1os desde que se cre\u00f3 inicialmente o se restableci\u00f3. Dominio:&nbsp;www.google.es Descripci\u00f3n: Cookie de Google. &nbsp; &nbsp; GARANT\u00cdAS Y OPCIONES SOBRE LAS COOKIES En todo momento, y al menos, durante la instalaci\u00f3n o puesta al d\u00eda del navegador,&nbsp;el usuario tiene la posibilidad de aceptar o rechazar la instalaci\u00f3n de cookies, o bien rechazar la instalaci\u00f3n de las cookies de terceros. Adem\u00e1s, despu\u00e9s de cada sesi\u00f3n puede eliminar todas o algunas de las cookies almacenadas. Asimismo, el usuario puede activar: &nbsp; La navegaci\u00f3n privada, mediante la cual su navegador deja de guardar el historial de navegaci\u00f3n, contrase\u00f1as de sitios web, cookies y otra informaci\u00f3n de las p\u00e1ginas que visita, o La funci\u00f3n de no rastrear, por la que el navegador pide a los sitios web que visita que no rastreen sus h\u00e1bitos de navegaci\u00f3n, para, por ejemplo, servirle publicidad de su inter\u00e9s en los sitios que visita. &nbsp; Le recomendamos que consulte la ayuda de su navegador para informarse de las diferentes opciones sobre c\u00f3mo gestionar las cookies. A continuaci\u00f3n, incluimos los v\u00ednculos para gestionar cookies en los navegadores m\u00e1s relevantes: Chrome:&nbsp;http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647 Firefox:&nbsp;Limpiar cookies en firefox Internet Explorer:&nbsp;Eliminar y administrar cookies Microsoft Safari:&nbsp;https:\/\/www.apple.com\/legal\/privacy\/es\/cookies\/ El usuario puede revocar su consentimiento para el uso de cookies en su navegador a trav\u00e9s de las opciones de configuraci\u00f3n, as\u00ed como a trav\u00e9s de los enlaces de terceros. Si no quiere que Google Analytics recoja y utilice informaci\u00f3n puede instalar un sistema de rechazo en su navegador a trav\u00e9s del siguiente enlace:&nbsp; https:\/\/tools.google.com\/dlpage\/gaoptout?hl=None ATENCI\u00d3N: Tenga en cuenta que el bloqueo de cookies puede afectar a todas o algunas de las funcionalidades de nuestra web.","og_url":"https:\/\/ispgestion.com\/it\/39363-home\/politica-de-cookies\/","og_site_name":"ISP Gesti\u00f3n","article_publisher":"https:\/\/www.facebook.com\/ispgestion\/","article_modified_time":"2022-03-12T09:14:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ispgestion.com\/39363-home\/politica-de-cookies\/","url":"https:\/\/ispgestion.com\/39363-home\/politica-de-cookies\/","name":"Pol\u00edtica de Cookies - ISP Gesti\u00f3n","isPartOf":{"@id":"https:\/\/ispgestion.com\/#website"},"datePublished":"2020-04-03T06:58:11+00:00","dateModified":"2022-03-12T09:14:00+00:00","breadcrumb":{"@id":"https:\/\/ispgestion.com\/39363-home\/politica-de-cookies\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ispgestion.com\/39363-home\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ispgestion.com\/39363-home\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ispgestion.com\/"},{"@type":"ListItem","position":2,"name":"Home, Isp Gesti\u00f3n","item":"https:\/\/ispgestion.com\/"},{"@type":"ListItem","position":3,"name":"Pol\u00edtica de Cookies"}]},{"@type":"WebSite","@id":"https:\/\/ispgestion.com\/#website","url":"https:\/\/ispgestion.com\/","name":"Gestione ISP","description":"Software cloud per ISP - Software ERP","publisher":{"@id":"https:\/\/ispgestion.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ispgestion.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ispgestion.com\/#organization","name":"Gestione ISP","url":"https:\/\/ispgestion.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ispgestion.com\/#\/schema\/logo\/image\/","url":"https:\/\/ispgestion.com\/wp-content\/uploads\/2020\/04\/cropped-logo-isp-1-1.png","contentUrl":"https:\/\/ispgestion.com\/wp-content\/uploads\/2020\/04\/cropped-logo-isp-1-1.png","width":245,"height":250,"caption":"ISP Gesti\u00f3n"},"image":{"@id":"https:\/\/ispgestion.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ispgestion\/","https:\/\/es.linkedin.com\/in\/isp-gesti\u00f3n-62652715a","https:\/\/www.youtube.com\/channel\/UCkZAs-0NFnSnVrh17SNCARg"]}]}},"_links":{"self":[{"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/pages\/268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/comments?post=268"}],"version-history":[{"count":10,"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/pages\/268\/revisions"}],"predecessor-version":[{"id":4788,"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/pages\/268\/revisions\/4788"}],"up":[{"embeddable":true,"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/pages\/40"}],"wp:attachment":[{"href":"https:\/\/ispgestion.com\/it\/wp-json\/wp\/v2\/media?parent=268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}